{"id":16899,"date":"2025-03-12T14:51:22","date_gmt":"2025-03-12T06:51:22","guid":{"rendered":"https:\/\/www.agriculture-machine.com\/?post_type=info&#038;p=16899"},"modified":"2025-03-12T14:51:23","modified_gmt":"2025-03-12T06:51:23","slug":"silage-chopping-machine-to-uganda","status":"publish","type":"info","link":"https:\/\/www.agriculture-machine.com\/hi\/silage-chopping-machine-to-uganda\/","title":{"rendered":"\u0909\u0917\u093e\u0902\u0921\u093e \u092e\u0947\u0902 250 \u0938\u093f\u0932\u093e\u091c \u091a\u0949\u092a\u093f\u0902\u0917 \u092e\u0936\u0940\u0928 \u0915\u0940 \u0938\u092b\u0932 \u0921\u093f\u0932\u0940\u0935\u0930\u0940"},"content":{"rendered":"<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-top\"     data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;16899&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;top&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;94&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;4.9&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;Rate this info&quot;,&quot;legend&quot;:&quot;4.9\\\/5 - (94 votes)&quot;,&quot;size&quot;:&quot;24&quot;,&quot;title&quot;:&quot;Successful Delivery of 250 Silage Chopping Machines to Uganda&quot;,&quot;width&quot;:&quot;139.6&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>              <div class=\"kksr-stars\">      <div class=\"kksr-stars-inactive\">             <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>     <\/div>      <div class=\"kksr-stars-active\" style=\"width: 139.6px;\">             <div class=\"kksr-star\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>     <\/div> <\/div>                   <div class=\"kksr-legend\" style=\"font-size: 19.2px;\">             4.9\/5 - (94 \u0935\u094b\u091f)    <\/div>     <\/div>  <p>Uganda&#8217;s agriculture sector is spearheading a national livestock initiative to procure 250 silage chopping machines. This effort is designed to enhance the efficiency of pasture processing and tackle the shortage of fodder during the dry season. <\/p>    <p>\u0909\u092a\u0915\u0930\u0923 \u0915\u094b \u0909\u0937\u094d\u0923\u0915\u091f\u093f\u092c\u0902\u0927\u0940\u092f \u091c\u0932\u0935\u093e\u092f\u0941 \u0915\u0947 \u0905\u0928\u0941\u0938\u093e\u0930 tailor \u0915\u093f\u092f\u093e \u091c\u093e\u0928\u093e \u091a\u093e\u0939\u093f\u090f \u0914\u0930 deployment \u0915\u0947 \u0932\u093f\u090f \u0909\u091a\u094d\u091a \u0909\u0924\u094d\u092a\u093e\u0926\u0915\u0924\u093e, \u0938\u094d\u0925\u093e\u092f\u093f\u0924\u094d\u0935, \u0914\u0930 \u0915\u092e \u0930\u0916\u0930\u0916\u093e\u0935 \u0932\u093e\u0917\u0924 should feature \u0939\u094b\u0928\u0940 \u091a\u093e\u0939\u093f\u090f 20 \u0915\u0943\u0937\u093f \u092a\u094d\u0930\u0926\u0930\u094d\u0936\u0928 \u0915\u094d\u0937\u0947\u0924\u094d\u0930\u094b\u0902 \u092e\u0947\u0902\u0964<\/p>    <figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\"> <figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" data-id=\"16901\" src=\"https:\/\/www.agriculture-machine.com\/wp-content\/uploads\/2025\/03\/forage-choppers-for-sale.webp\" alt=\"forage choppers for sale\" class=\"wp-image-16901\" srcset=\"https:\/\/www.agriculture-machine.com\/wp-content\/uploads\/2025\/03\/forage-choppers-for-sale.webp 720w, https:\/\/www.agriculture-machine.com\/wp-content\/uploads\/2025\/03\/forage-choppers-for-sale-360x270.webp 360w, https:\/\/www.agriculture-machine.com\/wp-content\/uploads\/2025\/03\/forage-choppers-for-sale-240x180.webp 240w, https:\/\/www.agriculture-machine.com\/wp-content\/uploads\/2025\/03\/forage-choppers-for-sale-16x12.webp 16w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><figcaption class=\"wp-element-caption\">forage choppers for sale<\/figcaption><\/figure>    <figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" data-id=\"16902\" src=\"https:\/\/www.agriculture-machine.com\/wp-content\/uploads\/2025\/03\/hay-chopping-machines.webp\" alt=\"hay chopping machines\" class=\"wp-image-16902\" srcset=\"https:\/\/www.agriculture-machine.com\/wp-content\/uploads\/2025\/03\/hay-chopping-machines.webp 720w, https:\/\/www.agriculture-machine.com\/wp-content\/uploads\/2025\/03\/hay-chopping-machines-360x270.webp 360w, https:\/\/www.agriculture-machine.com\/wp-content\/uploads\/2025\/03\/hay-chopping-machines-240x180.webp 240w, https:\/\/www.agriculture-machine.com\/wp-content\/uploads\/2025\/03\/hay-chopping-machines-16x12.webp 16w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><figcaption class=\"wp-element-caption\">hay chopping machines<\/figcaption><\/figure> <\/figure>    <h2 class=\"wp-block-heading\">\u091a\u091f\u093e\u0908 \u091a\u0949\u092a\u0930 \u092e\u0936\u0940\u0928 \u0915\u093e Mass \u0909\u0924\u094d\u092a\u093e\u0926\u0928<\/h2>    <ol class=\"wp-block-list\"> <li>\u092b\u0948\u0915\u094d\u091f\u094d\u0930\u0940 \u0928\u0947 manganese steel blades \u0914\u0930 \u092a\u0942\u0930\u0940 \u0924\u0930\u0939 \u092c\u0902\u0926 \u092e\u094b\u091f\u0930 \u0915\u0947 \u0938\u093e\u0925 \u090f\u0915 \u0935\u093f\u0936\u093f\u0937\u094d\u091f \u0909\u0924\u094d\u092a\u093e\u0926\u0928 \u0932\u093e\u0907\u0928 \u0936\u0941\u0930\u0942 \u0915\u0940 \u0939\u0948 \u0924\u093e\u0915\u093f \u0915\u0920\u094b\u0930\u0924\u093e \u0914\u0930 \u0927\u0942\u0932-\u0930\u094b\u0927 \u092e\u093e\u0928\u0915\u094b\u0902 \u0926\u094b\u0928\u094b\u0902 \u0915\u094b \u092a\u0942\u0930\u093e \u0915\u093f\u092f\u093e \u091c\u093e \u0938\u0915\u0947\u0964 <\/li>    <li>\u090f\u0915 \u092e\u0949\u0921\u094d\u092f\u0942\u0932\u0930 \u0905\u0938\u0947\u092e\u094d\u092c\u0932\u0940 \u0926\u0943\u0937\u094d\u091f\u093f\u0915\u094b\u0923 \u0915\u0947 \u0938\u093e\u0925, \u0939\u092e \u0915\u0947\u0935\u0932 15 \u0926\u093f\u0928\u094b\u0902 \u092e\u0947\u0902 250 \u0938\u0947\u091f \u0909\u092a\u0915\u0930\u0923 \u092a\u0942\u0930\u0947 \u0915\u0930 \u0938\u0915\u0924\u0947 \u0939\u0948\u0902, \u092a\u094d\u0930\u0924\u094d\u092f\u0947\u0915 \u092e\u0936\u0940\u0928 8-12 \u091f\u0928 \u092a\u094d\u0930\u0924\u093f \u0918\u0902\u091f\u0947 \u092a\u094d\u0930\u094b\u0938\u0947\u0938 \u0915\u0930\u0928\u0947 \u092e\u0947\u0902 \u0938\u0915\u094d\u0937\u092e \u0939\u0948\u0964 \u092f\u0939 \u0938\u0947\u091f\u0905\u092a \u0935\u093f\u0935\u093f\u0927 \u0915\u091a\u094d\u091a\u0947 \u092a\u0926\u093e\u0930\u094d\u0925\u094b\u0902, \u091c\u0948\u0938\u0947 \u092e\u0915\u094d\u0915\u093e \u0915\u0947 stalks \u0914\u0930 \u0939\u093e\u0925\u0940 \u0918\u093e\u0938, \u0915\u094b \u0938\u0902\u092d\u093e\u0932\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u092a\u0930\u094d\u092f\u093e\u092a\u094d\u0924 \u092c\u0939\u0941\u092e\u0941\u0916\u0940 \u0939\u0948\u0964 <\/li>    <li>\u0915\u091f\u093e\u0908 \u0938\u092e\u093e\u0928\u0924\u093e \u0938\u0941\u0928\u093f\u0936\u094d\u091a\u093f\u0924 \u0915\u0930\u0928\u0947 \u0914\u0930 \u092e\u094b\u091f\u0930 \u0924\u093e\u092a \u0935\u0943\u0926\u094d\u0927\u093f \u0915\u0940 \u0928\u093f\u0917\u0930\u093e\u0928\u0940 \u0915\u0947 \u0932\u093f\u090f \u0928\u092e\u0942\u0928\u093e \u0909\u092a\u0915\u0930\u0923\u094b\u0902 \u0915\u094b \u0938\u0916\u094d\u0924 72-\u0918\u0902\u091f\u0947 \u092a\u0930\u0940\u0915\u094d\u0937\u0923 \u0905\u0935\u0927\u093f \u0938\u0947 \u0917\u0941\u091c\u0930\u0928\u093e \u092a\u0921\u093c\u0924\u093e \u0939\u0948\u0964 \u0938\u093e\u0925 \u0939\u0940, \u092f\u0939 48 \u0918\u0902\u091f\u0947 \u0915\u0947 \u0932\u093f\u090f \u0909\u091a\u094d\u091a \u0924\u093e\u092a\u092e\u093e\u0928 \u0914\u0930 \u0909\u091a\u094d\u091a \u0906\u0930\u094d\u0926\u094d\u0930\u0924\u093e \u0938\u094d\u0925\u093f\u0924\u093f\u092f\u094b\u0902 \u092e\u0947\u0902 \u092d\u0940 \u091a\u0932\u093e\u092f\u093e \u0917\u092f\u093e \u0924\u093e\u0915\u093f \u0938\u094d\u0925\u093f\u0930\u0924\u093e \u0915\u0940 \u092a\u0941\u0937\u094d\u091f\u093f \u0939\u094b \u0938\u0915\u0947\u0964 <\/li>    <li>\u092c\u094d\u0932\u0947\u0921 \u091c\u0902\u0917-\u0930\u094b\u0927\u0915 \u092c\u0928\u093e\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f treated \u0939\u0948\u0902 \u0914\u0930 \u0935\u0947 \u0935\u094d\u092f\u0915\u094d\u0924\u093f\u0917\u0924 \u0930\u0942\u092a \u0938\u0947 encapsulated \u0939\u0948\u0902, \u091c\u092c\u0915\u093f \u092e\u094b\u091f\u0930 \u0914\u0930 \u0921\u094d\u0930\u093e\u0907\u0935 \u0938\u093f\u0938\u094d\u091f\u092e cushioning \u092a\u0926\u093e\u0930\u094d\u0925\u094b\u0902 \u0938\u0947 \u0938\u0902\u0930\u0915\u094d\u0937\u093f\u0924 \u0939\u0948\u0902\u0964 \u0939\u0930 \u0905\u0928\u0941\u0915\u0942\u0932\u093f\u0924 \u0935\u0941\u0921\u0928 \u0915\u0947\u0938 \u092f\u0939 moisture-proof \u0914\u0930 damage-proof \u092c\u0928\u093e\u0915\u0930 \u0921\u093f\u091c\u093c\u093e\u0907\u0928 \u0915\u093f\u092f\u093e \u0917\u092f\u093e \u0939\u0948, \u091c\u094b \u0938\u092e\u0941\u0926\u094d\u0930\u0940 \u092a\u0930\u093f\u0935\u0939\u0928 \u0915\u0947 \u0932\u093f\u090f \u0906\u0926\u0930\u094d\u0936 \u0939\u0948\u0964<\/li> <\/ol>    <figure class=\"wp-block-gallery has-nested-images columns-2 is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\"> <figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" data-id=\"16904\" src=\"https:\/\/www.agriculture-machine.com\/wp-content\/uploads\/2025\/03\/silage-cutter-machines-in-factory.webp\" alt=\"\u092b\u0948\u0915\u094d\u091f\u0930\u0940 \u092e\u0947\u0902 \u0938\u093f\u0932\u0947\u091c \u0915\u091f\u0930 \u092e\u0936\u0940\u0928\u0947\u0902\" class=\"wp-image-16904\" srcset=\"https:\/\/www.agriculture-machine.com\/wp-content\/uploads\/2025\/03\/silage-cutter-machines-in-factory.webp 720w, https:\/\/www.agriculture-machine.com\/wp-content\/uploads\/2025\/03\/silage-cutter-machines-in-factory-360x270.webp 360w, https:\/\/www.agriculture-machine.com\/wp-content\/uploads\/2025\/03\/silage-cutter-machines-in-factory-240x180.webp 240w, https:\/\/www.agriculture-machine.com\/wp-content\/uploads\/2025\/03\/silage-cutter-machines-in-factory-16x12.webp 16w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><figcaption class=\"wp-element-caption\">\u092b\u0948\u0915\u094d\u091f\u0930\u0940 \u092e\u0947\u0902 \u0938\u093f\u0932\u0947\u091c \u0915\u091f\u0930 \u092e\u0936\u0940\u0928\u0947\u0902<\/figcaption><\/figure>    <figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" data-id=\"16903\" src=\"https:\/\/www.agriculture-machine.com\/wp-content\/uploads\/2025\/03\/silage-chopping-machines.webp\" alt=\"silage chopping machines\" class=\"wp-image-16903\" srcset=\"https:\/\/www.agriculture-machine.com\/wp-content\/uploads\/2025\/03\/silage-chopping-machines.webp 720w, https:\/\/www.agriculture-machine.com\/wp-content\/uploads\/2025\/03\/silage-chopping-machines-360x270.webp 360w, https:\/\/www.agriculture-machine.com\/wp-content\/uploads\/2025\/03\/silage-chopping-machines-240x180.webp 240w, https:\/\/www.agriculture-machine.com\/wp-content\/uploads\/2025\/03\/silage-chopping-machines-16x12.webp 16w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><figcaption class=\"wp-element-caption\">silage chopping machines<\/figcaption><\/figure>    <figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"405\" height=\"540\" data-id=\"16905\" src=\"https:\/\/www.agriculture-machine.com\/wp-content\/uploads\/2025\/03\/chaff-cutter-internal-details-405x540.webp\" alt=\"chaff cutter internal details\" class=\"wp-image-16905\" srcset=\"https:\/\/www.agriculture-machine.com\/wp-content\/uploads\/2025\/03\/chaff-cutter-internal-details-405x540.webp 405w, https:\/\/www.agriculture-machine.com\/wp-content\/uploads\/2025\/03\/chaff-cutter-internal-details-203x270.webp 203w, https:\/\/www.agriculture-machine.com\/wp-content\/uploads\/2025\/03\/chaff-cutter-internal-details-9x12.webp 9w, https:\/\/www.agriculture-machine.com\/wp-content\/uploads\/2025\/03\/chaff-cutter-internal-details.webp 540w\" sizes=\"auto, (max-width: 405px) 100vw, 405px\" \/><figcaption class=\"wp-element-caption\">chaff cutter internal details<\/figcaption><\/figure>    <figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"405\" height=\"540\" data-id=\"16906\" src=\"https:\/\/www.agriculture-machine.com\/wp-content\/uploads\/2025\/03\/fodder-chopper-blades-405x540.webp\" alt=\"fodder chopper blades\" class=\"wp-image-16906\" srcset=\"https:\/\/www.agriculture-machine.com\/wp-content\/uploads\/2025\/03\/fodder-chopper-blades-405x540.webp 405w, https:\/\/www.agriculture-machine.com\/wp-content\/uploads\/2025\/03\/fodder-chopper-blades-203x270.webp 203w, https:\/\/www.agriculture-machine.com\/wp-content\/uploads\/2025\/03\/fodder-chopper-blades-9x12.webp 9w, https:\/\/www.agriculture-machine.com\/wp-content\/uploads\/2025\/03\/fodder-chopper-blades.webp 540w\" sizes=\"auto, (max-width: 405px) 100vw, 405px\" \/><figcaption class=\"wp-element-caption\">fodder chopper blades<\/figcaption><\/figure> <\/figure>    <h2 class=\"wp-block-heading\">Machine packaging \u0914\u0930 logistics<\/h2>    <p class=\"translation-block\">\u0939\u092e\u0928\u0947 250 \u0907\u0915\u093e\u0907\u092f\u094b\u0902 \u0915\u094b <strong><em><a href=\"https:\/\/www.agriculture-machine.com\/hi\/chaff-cutter-and-grain-crusher\/\">silage chopping machines<\/a><\/em><\/strong> \u092e\u0947\u0902 \u0915\u0908 \u0915\u0902\u091f\u0947\u0928\u0930\u094b\u0902 \u092e\u0947\u0902 \u092a\u0948\u0915 \u0914\u0930 \u0936\u093f\u092a \u0915\u093f\u092f\u093e\u0964 \u0939\u092e\u093e\u0930\u0940 \u0924\u0915\u0928\u0940\u0915\u0940 \u091f\u0940\u092e <a href=\"https:\/\/en.wikipedia.org\/wiki\/Uganda\" target=\"_blank\" rel=\"noopener\">\u092f\u0942\u0917\u093e\u0902\u0921\u093e<\/a> \u092d\u0940 unloading, installation, \u0914\u0930 operation training \u092e\u0947\u0902 \u092e\u0926\u0926 \u0915\u0947 \u0932\u093f\u090f \u0917\u0908, \u0924\u093e\u0915\u093f \u0909\u092a\u0915\u0930\u0923 \u0909\u0924\u094d\u092a\u093e\u0926\u0928 \u0915\u0947 \u0932\u093f\u090f \u0938\u0947\u091f \u0939\u094b \u0938\u0915\u0947\u0964 <\/p>    <figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-4 is-layout-flex wp-block-gallery-is-layout-flex\"> <figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" data-id=\"16907\" src=\"https:\/\/www.agriculture-machine.com\/wp-content\/uploads\/2025\/03\/crop-choppers-for-sale.webp\" alt=\"crop choppers for sale\" class=\"wp-image-16907\" srcset=\"https:\/\/www.agriculture-machine.com\/wp-content\/uploads\/2025\/03\/crop-choppers-for-sale.webp 720w, https:\/\/www.agriculture-machine.com\/wp-content\/uploads\/2025\/03\/crop-choppers-for-sale-360x270.webp 360w, https:\/\/www.agriculture-machine.com\/wp-content\/uploads\/2025\/03\/crop-choppers-for-sale-240x180.webp 240w, https:\/\/www.agriculture-machine.com\/wp-content\/uploads\/2025\/03\/crop-choppers-for-sale-16x12.webp 16w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><figcaption class=\"wp-element-caption\">crop choppers for sale<\/figcaption><\/figure>    <figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" data-id=\"16908\" src=\"https:\/\/www.agriculture-machine.com\/wp-content\/uploads\/2025\/03\/green-fodder-choppers-loading-site.webp\" alt=\"green fodder choppers loading site\" class=\"wp-image-16908\" srcset=\"https:\/\/www.agriculture-machine.com\/wp-content\/uploads\/2025\/03\/green-fodder-choppers-loading-site.webp 720w, https:\/\/www.agriculture-machine.com\/wp-content\/uploads\/2025\/03\/green-fodder-choppers-loading-site-360x270.webp 360w, https:\/\/www.agriculture-machine.com\/wp-content\/uploads\/2025\/03\/green-fodder-choppers-loading-site-240x180.webp 240w, https:\/\/www.agriculture-machine.com\/wp-content\/uploads\/2025\/03\/green-fodder-choppers-loading-site-16x12.webp 16w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><figcaption class=\"wp-element-caption\">green fodder choppers loading site<\/figcaption><\/figure> <\/figure>    <p>\u092f\u0939 \u0938\u0939\u092f\u094b\u0917 \u0939\u092e\u093e\u0930\u0947 \u0905\u092b\u094d\u0930\u0940\u0915\u0940 \u0938\u0930\u0915\u093e\u0930 \u092a\u0930\u093f\u092f\u094b\u091c\u0928\u093e\u0913\u0902 \u0915\u0947 \u092d\u0940\u0924\u0930 \u0915\u0943\u0937\u093f \u092e\u0936\u0940\u0928\u0930\u0940 \u0915\u0947 \u092a\u0948\u092e\u093e\u0928\u0947 \u092e\u0947\u0902 \u090f\u0915 \u092e\u0939\u0924\u094d\u0935\u092a\u0942\u0930\u094d\u0923 \u0909\u0928\u094d\u0928\u0924\u093f \u0915\u093e \u092a\u094d\u0930\u0924\u093f\u0928\u093f\u0927\u093f\u0924\u094d\u0935 \u0915\u0930\u0924\u093e \u0939\u0948\u0964 \u0939\u092e \u0938\u0924\u0924 \u0915\u0943\u0937\u093f \u092e\u0947\u0902 \u0905\u092a\u0928\u0947 \u0926\u0940\u0930\u094d\u0918\u0915\u093e\u0932\u093f\u0915 \u092d\u093e\u0917\u0940\u0926\u093e\u0930\u0940 \u0915\u094b \u092e\u091c\u092c\u0942\u0924 \u0915\u0930\u0928\u0947 \u0915\u0947 \u0932\u093f\u090f \u0905\u0917\u094d\u0930\u0938\u0930 \u0939\u0948\u0902\u0964 \u092f\u0926\u093f \u0906\u092a\u0915\u094b \u0915\u093f\u0938\u0940 \u0905\u0924\u093f\u0930\u093f\u0915\u094d\u0924 \u091c\u093e\u0928\u0915\u093e\u0930\u0940 \u0915\u0940 \u0906\u0935\u0936\u094d\u092f\u0915\u0924\u093e \u0939\u094b \u0924\u094b \u0915\u0943\u092a\u092f\u093e \u0938\u0902\u092a\u0930\u094d\u0915 \u0915\u0930\u0947\u0902\u0964<\/p>","protected":false},"excerpt":{"rendered":"<p>Uganda&#8217;s agricultural sector spearheaded the initiative to acquire 250 silage chopping machines, which we successfully won through international bidding and delivered promptly.<\/p>","protected":false},"author":1,"featured_media":16900,"parent":0,"template":"","tags":[591],"info-type":[20],"class_list":["post-16899","info","type-info","status-publish","has-post-thumbnail","hentry","tag-silage","info-type-case"],"_links":{"self":[{"href":"https:\/\/www.agriculture-machine.com\/hi\/wp-json\/wp\/v2\/info\/16899","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.agriculture-machine.com\/hi\/wp-json\/wp\/v2\/info"}],"about":[{"href":"https:\/\/www.agriculture-machine.com\/hi\/wp-json\/wp\/v2\/types\/info"}],"author":[{"embeddable":true,"href":"https:\/\/www.agriculture-machine.com\/hi\/wp-json\/wp\/v2\/users\/1"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.agriculture-machine.com\/hi\/wp-json\/wp\/v2\/media\/16900"}],"wp:attachment":[{"href":"https:\/\/www.agriculture-machine.com\/hi\/wp-json\/wp\/v2\/media?parent=16899"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.agriculture-machine.com\/hi\/wp-json\/wp\/v2\/tags?post=16899"},{"taxonomy":"info-type","embeddable":true,"href":"https:\/\/www.agriculture-machine.com\/hi\/wp-json\/wp\/v2\/info-type?post=16899"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}